{"id":49780,"date":"2026-09-02T10:22:25","date_gmt":"2026-09-02T14:22:25","guid":{"rendered":"https:\/\/foodbankscanada.ca\/?p=49780"},"modified":"2026-09-02T10:24:08","modified_gmt":"2026-09-02T14:24:08","slug":"nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada","status":"publish","type":"post","link":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/","title":{"rendered":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada"},"content":{"rendered":"\n<p>Alors que l\u2019\u00e9t\u00e9 tire \u00e0 sa fin, les enfants de partout au Canada se pr\u00e9parent \u00e0 la rentr\u00e9e. Alors que plusieurs transporteront des sacs \u00e0 dos remplis de stylos, de papier, de livres et de tablettes, c\u2019est ce qui se trouve dans leur ventre et leur bo\u00eete \u00e0 lunch qui pourrait avoir la plus grande influence sur leur r\u00e9ussite.&nbsp;<\/p>\n\n\n\n<p>Malheureusement, de nombreux \u00e9l\u00e8ves arrivent en classe le ventre vide.&nbsp;<\/p>\n\n\n\n<p>Il s\u2019agit d\u2019un probl\u00e8me que conna\u00eet tr\u00e8s bien l\u2019Arm\u00e9e du Salut de Fort Frances, qui exploite une banque alimentaire dans le nord de l\u2019Ontario. \u00ab\u202fDe nombreuses familles de la communaut\u00e9 sont confront\u00e9es \u00e0 des d\u00e9fis \u00e9conomiques, la hausse du co\u00fbt des aliments ayant une incidence sur le bien-\u00eatre des \u00e9l\u00e8ves\u202f\u00bb, a d\u00e9clar\u00e9 l\u2019organisme dans un rapport \u00e0 Banques alimentaires Canada. \u00ab\u202fLes \u00e9coles signalent une demande accrue pour des programmes de repas scolaires, car la faim nuit \u00e0 l\u2019apprentissage.\u202f\u00bb&nbsp;<\/p>\n\n\n\n<p>Fort Frances n\u2019est pas la seule communaut\u00e9 \u00e0 conna\u00eetre cette r\u00e9alit\u00e9.&nbsp;<a href=\"https:\/\/www150.statcan.gc.ca\/t1\/tbl1\/fr\/tv.action?pid=1310083401\" target=\"_blank\" rel=\"noreferrer noopener\">En 2024<\/a>,&nbsp;<strong>27\u202f%<\/strong>&nbsp;des familles biparentales avec enfants au Canada ont connu un certain niveau d\u2019ins\u00e9curit\u00e9 alimentaire. Cette statistique s\u2019\u00e9l\u00e8ve \u00e0&nbsp;<strong>44\u202f%<\/strong>&nbsp;chez les familles monoparentales.&nbsp;<a href=\"https:\/\/foodbankscanada.ca\/fr\/la-faim-au-canada\/bilan-faim\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Un tiers des clients des banques alimentaires du pays sont des enfants<\/strong><\/a>&nbsp;de&nbsp;moins de 18\u202fans.&nbsp;<\/p>\n\n\n\n<p>C\u2019est en partie la raison pour laquelle, en 2024, le gouvernement du Canada a annonc\u00e9 son&nbsp;<a href=\"https:\/\/www.canada.ca\/fr\/emploi-developpement-social\/programmes\/alimentation-ecoles\/nourrir-releve.html\" target=\"_blank\" rel=\"noreferrer noopener\">Programme national d\u2019alimentation scolaire<\/a>, qui investirait 1\u202fmilliard de dollars sur cinq ans dans des programmes d\u2019alimentation dans les \u00e9coles par l\u2019entremise des provinces, des territoires et des partenaires autochtones. En 2025,&nbsp;<a href=\"https:\/\/www.canada.ca\/fr\/emploi-developpement-social\/nouvelles\/2026\/06\/document-dinformation-vision-federale-du-programme-national-dalimentation-scolaire.html\" target=\"_blank\" rel=\"noreferrer noopener\">ce programme est devenu permanent<\/a>.<\/p>\n\n\n\n<p>En date de cette ann\u00e9e scolaire (2026-2027),&nbsp;<a href=\"https:\/\/www.canada.ca\/fr\/emploi-developpement-social\/nouvelles\/2026\/06\/le-programme-national-dalimentation-scolaire-prend-forme-partout-au-canada.html\" target=\"_blank\" rel=\"noreferrer noopener\">environ 80 % des \u00e9coles publiques du Canada<\/a>&nbsp;\u2013 y compris toutes celles de&nbsp;<a href=\"https:\/\/peischoolfood.ca\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019\u00ce.-P.-\u00c9,<\/a>&nbsp;de&nbsp;<a href=\"https:\/\/www.nslunch.ca\/fr\/page\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">la Nouvelle-\u00c9cosse<\/a>&nbsp;et du&nbsp;<a href=\"https:\/\/www.gnb.ca\/fr\/sujet\/education-formation\/m-12\/scolaire\/programmealimentation.html\" target=\"_blank\" rel=\"noreferrer noopener\">Nouveau-Brunswick<\/a>&nbsp;\u2013 offrent des programmes d\u2019alimentation gratuits ou abordables aux \u00e9l\u00e8ves. Le gouvernement f\u00e9d\u00e9ral vise \u00e0 renforcer ces progr\u00e8s et aider \u00e0 combler les lacunes restantes \u00e0 mesure que le Programme national d\u2019alimentation scolaire se poursuit.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-576x1024.png\" alt=\"\" class=\"wp-image-49783\" style=\"width:380px;height:auto\" srcset=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-576x1024.png 576w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-169x300.png 169w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-768x1365.png 768w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-864x1536.png 864w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-1152x2048.png 1152w, https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/Jasper-Food-Bank-scaled.png 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"wp-element-caption\"><em>Apr\u00e8s avoir re\u00e7u une subvention du Fonds pour l\u2019infrastructure alimentaire scolaire, la banque alimentaire de Jasper, en Alberta, a lanc\u00e9 un nouveau programme de petits d\u00e9jeuners dans deux \u00e9coles o\u00f9 il n\u2019y en avait pas auparavant.<\/em><\/figcaption><\/figure>\n\n\n\n<p>De nombreux programmes d\u2019alimentation scolaire \u2013\u202fprovinciaux, territoriaux, r\u00e9gionaux ou locaux\u202f\u2013 contr\u00f4lent les co\u00fbts et renforcent la communaut\u00e9 en \u00e9tablissant des partenariats avec des organismes sans but lucratif, comme les banques alimentaires, qui fournissent la nourriture ou pr\u00e9parent les repas.&nbsp;<\/p>\n\n\n\n<p>Un exemple de la fa\u00e7on dont cela peut fonctionner est&nbsp;<em>La Cantine pour tous,&nbsp;<\/em>actif dans 263\u202f\u00e9coles au Qu\u00e9bec. Cet organisme administre des programmes de d\u00eeners scolaires o\u00f9 les parents paient chaque repas \u00e0 la mesure de leurs moyens (entre 1\u202f$ et 6\u202f$ ou plus si les familles sont dispos\u00e9es \u00e0 offrir un soutien suppl\u00e9mentaire). Les familles qui ont command\u00e9 des repas sont consign\u00e9es, mais le montant qu\u2019elles ont pay\u00e9 ne l\u2019est pas\u202f: cela aide le programme \u00e0 \u00e9viter de stigmatiser les \u00e9l\u00e8ves.&nbsp;<\/p>\n\n\n\n<p>Parmi les partenaires de&nbsp;<em>La Cantine pour tous<\/em>, on compte des banques alimentaires, comme Moisson Beauce au sud de Qu\u00e9bec. La banque alimentaire fournit des repas aux \u00e9coles de la r\u00e9gion et re\u00e7oit des frais constants pour les services de&nbsp;<em>La Cantine pour tous<\/em>, qui recueille des fonds pour combler la diff\u00e9rence si le soutien gouvernemental et les paiements des familles ne&nbsp;couvrent pas les frais. Moisson Beauce investit ses modestes profits dans ses programmes d\u2019aide alimentaire destin\u00e9s aux personnes dans le besoin. Tout le monde y gagne.<\/p>\n\n\n\n<p>C\u2019est pourquoi, en compl\u00e9ment du Programme national d\u2019alimentation dans les \u00e9coles, Agriculture et Agroalimentaire Canada a lanc\u00e9 le&nbsp;<a href=\"https:\/\/agriculture.canada.ca\/fr\/programmes\/fonds-linfrastructure-alimentaire-scolaire\" target=\"_blank\" rel=\"noreferrer noopener\">Fonds pour l\u2019infrastructure alimentaire scolaire\u202f(FIAS)<\/a>, qui investit dans des infrastructures et de l\u2019\u00e9quipement permettant \u00e0 des organismes comme Moisson Beauce d\u2019am\u00e9liorer et d\u2019accro\u00eetre leur contribution aux programmes d\u2019alimentation dans les \u00e9coles.&nbsp;<\/p>\n\n\n\n<p>En 2025, Banques alimentaires Canada a \u00e9t\u00e9 choisi pour distribuer 1,6\u202fmillion de dollars en soutien au FIAS. La somme a \u00e9t\u00e9 accord\u00e9e \u00e0 24\u202fbanques alimentaires et organismes communautaires. Les fonds ont servi \u00e0\u202f:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>accro\u00eetre&nbsp;la capacit\u00e9 des banques alimentaires \u00e0 fournir des denr\u00e9es aux programmes scolaires locaux;&nbsp;<\/li>\n\n\n\n<li>am\u00e9liorer&nbsp;la disponibilit\u00e9 d\u2019aliments nutritifs et culturellement appropri\u00e9s dans ces programmes;&nbsp;<\/li>\n\n\n\n<li>\u00e9largir&nbsp;la port\u00e9e et l\u2019incidence de ces programmes.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Au total, ces investissements se sont traduits en nutrition imm\u00e9diate et r\u00e9currente pour&nbsp;<strong>plus de 8\u202f000<\/strong>\u202f\u00e9l\u00e8ves suppl\u00e9mentaires tout en renfor\u00e7ant la capacit\u00e9 alimentaire communautaire \u00e0 long terme.&nbsp;<\/p>\n\n\n\n<p>L\u2019Arm\u00e9e du Salut \u00e0 Fort Frances est l\u2019un des organismes qui&nbsp;ont&nbsp;re\u00e7u une partie de ces fonds. Avant de recevoir une subvention du FIAS, les b\u00e9n\u00e9voles utilisaient leur v\u00e9hicule personnel pour transporter de la nourriture, ce qui limitait la quantit\u00e9 et le type d\u2019aliments qui pouvait se rendre aux programmes alimentaires scolaires. Gr\u00e2ce \u00e0 l\u2019achat d\u2019un v\u00e9hicule de livraison sp\u00e9cialis\u00e9, l\u2019Arm\u00e9e du Salut a pu augmenter la quantit\u00e9 et la qualit\u00e9 des aliments fournis, livrant ainsi plus de&nbsp;<strong>quatre fois<\/strong>&nbsp;plus de repas aux \u00e9l\u00e8ves dans le besoin.&nbsp;<\/p>\n\n\n\n<p>L\u2019Arm\u00e9e du Salut de Fort Frances affirme que le financement du FIAS a jou\u00e9 un r\u00f4le essentiel dans la r\u00e9duction de l\u2019ins\u00e9curit\u00e9 alimentaire chez les \u00e9l\u00e8ves de la communaut\u00e9. L\u2019organisme signale que dans une \u00e9cole primaire, les \u00e9l\u00e8ves qui arrivaient auparavant \u00e0 la faim \u00e9taient nettement plus engag\u00e9s et concentr\u00e9s une fois que les mesures de soutien alimentaire ont \u00e9t\u00e9 mises en place. Un membre du personnel de l\u2019\u00e9cole a d\u00e9clar\u00e9\u202f: \u00ab\u202fNous avons constat\u00e9 un changement\u202f: les \u00e9l\u00e8ves sont plus calmes, plus aptes \u00e0 se concentrer et plus dispos\u00e9s \u00e0 participer en classe avec le ventre plein.\u202f\u00bb&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-acces-et-qualite-nbsp\"><strong>Acc\u00e8s et qualit\u00e9<\/strong>&nbsp;<\/h3>\n\n\n\n<p>Les recherches d\u00e9montrent que l\u2019acc\u00e8s aux aliments est important dans un contexte d\u2019apprentissage. Lorsque les enfants ont faim \u00e0 l\u2019\u00e9cole, leur niveau d\u2019\u00e9nergie, leur m\u00e9moire, leurs comp\u00e9tences en r\u00e9solution de probl\u00e8mes et d\u2019autres fonctions cognitives sont tous affect\u00e9s n\u00e9gativement. Une bonne alimentation am\u00e9liore aussi la fr\u00e9quentation scolaire. Par exemple,&nbsp;<a href=\"https:\/\/www.maxwell.syr.edu\/research\/lerner-center\/population-health-research-brief-series\/article\/exposure-to-free-school-meals-in-kindergarten-has-lasting-positive-effects-on-students-attendance\" target=\"_blank\" rel=\"noreferrer noopener\">une \u00e9tude<\/a>&nbsp;men\u00e9e aupr\u00e8s des \u00e9l\u00e8ves de maternelle \u00e0 New\u202fYork a r\u00e9v\u00e9l\u00e9 que l\u2019acc\u00e8s \u00e0 des repas gratuits \u00e0 l\u2019\u00e9cole r\u00e9duisait l\u2019absent\u00e9isme chronique de 5,4\u202f%.&nbsp;<\/p>\n\n\n\n<p>Les types d\u2019aliments fournis sont \u00e9galement importants.&nbsp;Les habitudes alimentaires au Canada&nbsp;laissent \u00e0 d\u00e9sirer. Les enqu\u00eates sur la sant\u00e9 de Statistique Canada montrent que seule une minorit\u00e9 de personnes\u202f\u2013&nbsp;y compris les enfants\u202f\u2013&nbsp;consomment la quantit\u00e9 recommand\u00e9e de fruits ou de l\u00e9gumes chaque jour.&nbsp;<\/p>\n\n\n\n<p>Gr\u00e2ce au FIAS, les banques alimentaires et les organismes communautaires s\u2019efforcent non seulement de fournir suffisamment de nourriture aux \u00e9l\u00e8ves, mais aussi les bons types d\u2019aliments pour stimuler l\u2019apprentissage et le d\u00e9veloppement.&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fAvant que la banque alimentaire re\u00e7oive le nouveau r\u00e9frig\u00e9rateur et cong\u00e9lateur, notre programme de livraison scolaire devait souvent limiter les produits frais en raison du manque d\u2019espace d\u2019entreposage\u202f\u00bb, rapporte Ardis\u202fProulx-Chedore, de la Cochrane Food Bank, \u00e0 Cochrane, en Ontario. \u00ab\u202fDepuis l\u2019installation, nous avons pu garder \u00e0 port\u00e9e de main de plus grandes quantit\u00e9s de fruits, de l\u00e9gumes, de produits laitiers et de collations pr\u00e9par\u00e9es et les livrer syst\u00e9matiquement aux \u00e9coles.\u202f\u00bb&nbsp;<\/p>\n\n\n\n<p>Une \u00e9ducatrice d\u2019une \u00e9cole desservie par la banque alimentaire de Cochrane a d\u00e9clar\u00e9\u202f: \u00ab\u202fLa diff\u00e9rence est remarquable. Les \u00e9l\u00e8ves qui sautaient le d\u00e9jeuner ont maintenant acc\u00e8s \u00e0 des denr\u00e9es fra\u00eeches chaque jour, et nous constatons des am\u00e9liorations dans leur concentration et leur comportement.\u202f\u00bb&nbsp;<\/p>\n\n\n\n<p>\u00ab\u202fGr\u00e2ce au FIAS, nous avons constat\u00e9 une r\u00e9duction importante de l\u2019ins\u00e9curit\u00e9 alimentaire dans notre quartier\u202f\u00bb, rapporte Samantha\u202fCampbell, de Moosomin Food Share, \u00e0 Moosomin, en Saskatchewan. \u00ab\u202fLes familles qui avaient du mal \u00e0 pr\u00e9parer des repas \u00e9quilibr\u00e9s ont maintenant acc\u00e8s \u00e0 des produits frais et locaux, ce qui a am\u00e9lior\u00e9 leur sant\u00e9 et leur stabilit\u00e9 financi\u00e8re.\u202f\u00bb&nbsp;<\/p>\n\n\n\n<p><em>Banques alimentaires Canada collabore \u00e9galement avec les banques alimentaires de partout au pays pour offrir un soutien alimentaire aux enfants pendant les mois d\u2019\u00e9t\u00e9, lorsque les programmes de repas scolaires ne sont pas disponibles.&nbsp;<\/em><a href=\"https:\/\/foodbankscanada.ca\/fr\/apres-la-cloche\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cliquez ici<\/a>&nbsp;pour&nbsp;en savoir plus sur notre programme Apr\u00e8s la cloche.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que l\u2019\u00e9t\u00e9 tire \u00e0 sa fin, les enfants de partout au Canada se pr\u00e9parent \u00e0 la rentr\u00e9e. Alors que plusieurs transporteront des sacs \u00e0 dos remplis de stylos, de papier, de livres et de tablettes, c\u2019est ce qui se trouve dans leur ventre et leur bo\u00eete \u00e0 lunch qui pourrait avoir la plus grande&#8230;<\/p>\n","protected":false},"author":34,"featured_media":49786,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_yoast_wpseo_focuskw":"","_yoast_wpseo_title":"","_yoast_wpseo_metadesc":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_opengraph-image":"","_yoast_wpseo_opengraph-image-id":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_twitter-image":"","_yoast_wpseo_twitter-image-id":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-49780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v26.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada - Banques alimentaires Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada\" \/>\n<meta property=\"og:description\" content=\"Alors que l\u2019\u00e9t\u00e9 tire \u00e0 sa fin, les enfants de partout au Canada se pr\u00e9parent \u00e0 la rentr\u00e9e. Alors que plusieurs transporteront des sacs \u00e0 dos remplis de stylos, de papier, de livres et de tablettes, c\u2019est ce qui se trouve dans leur ventre et leur bo\u00eete \u00e0 lunch qui pourrait avoir la plus grande...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"Banques alimentaires Canada\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T14:22:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T14:24:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Samantha Rideout\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Samantha Rideout\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\"},\"author\":{\"name\":\"Samantha Rideout\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/6cc54c832653dce5f336a8e850d98f1f\"},\"headline\":\"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada\",\"datePublished\":\"2026-09-02T14:22:25+00:00\",\"dateModified\":\"2026-09-02T14:24:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\"},\"wordCount\":1485,\"publisher\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\",\"name\":\"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada - Banques alimentaires Canada\",\"isPartOf\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg\",\"datePublished\":\"2026-09-02T14:22:25+00:00\",\"dateModified\":\"2026-09-02T14:24:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage\",\"url\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg\",\"contentUrl\":\"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg\",\"width\":2121,\"height\":1414,\"caption\":\"Elementary Pupils Enjoying Healthy Lunch In Cafeteria Using Knife And Fork\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/foodbankscanada.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#website\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"name\":\"Banques alimentaires Canada\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#organization\",\"name\":\"Food Banks Canada\",\"url\":\"https:\/\/foodbankscanada.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"contentUrl\":\"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png\",\"width\":377,\"height\":89,\"caption\":\"Food Banks Canada\"},\"image\":{\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/6cc54c832653dce5f336a8e850d98f1f\",\"name\":\"Samantha Rideout\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0436ecff73810150cca59d2521277072f37caf478cd16af70844347e0259cde6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0436ecff73810150cca59d2521277072f37caf478cd16af70844347e0259cde6?s=96&d=mm&r=g\",\"caption\":\"Samantha Rideout\"},\"url\":\"https:\/\/foodbankscanada.ca\/fr\/author\/samantha-rideoutfoodbankscanada-ca\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada - Banques alimentaires Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/","og_locale":"fr_CA","og_type":"article","og_title":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada","og_description":"Alors que l\u2019\u00e9t\u00e9 tire \u00e0 sa fin, les enfants de partout au Canada se pr\u00e9parent \u00e0 la rentr\u00e9e. Alors que plusieurs transporteront des sacs \u00e0 dos remplis de stylos, de papier, de livres et de tablettes, c\u2019est ce qui se trouve dans leur ventre et leur bo\u00eete \u00e0 lunch qui pourrait avoir la plus grande...","og_url":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/","og_site_name":"Banques alimentaires Canada","article_published_time":"2026-09-02T14:22:25+00:00","article_modified_time":"2026-09-02T14:24:08+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg","type":"image\/jpeg"}],"author":"Samantha Rideout","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Samantha Rideout","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#article","isPartOf":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/"},"author":{"name":"Samantha Rideout","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/6cc54c832653dce5f336a8e850d98f1f"},"headline":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada","datePublished":"2026-09-02T14:22:25+00:00","dateModified":"2026-09-02T14:24:08+00:00","mainEntityOfPage":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/"},"wordCount":1485,"publisher":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#organization"},"image":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/","url":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/","name":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada - Banques alimentaires Canada","isPartOf":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage"},"image":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg","datePublished":"2026-09-02T14:22:25+00:00","dateModified":"2026-09-02T14:24:08+00:00","breadcrumb":{"@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#primaryimage","url":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg","contentUrl":"https:\/\/content.foodbankscanada.ca\/wordpress\/2026\/09\/GettyImages-178085860-1.jpg","width":2121,"height":1414,"caption":"Elementary Pupils Enjoying Healthy Lunch In Cafeteria Using Knife And Fork"},{"@type":"BreadcrumbList","@id":"https:\/\/foodbankscanada.ca\/fr\/nourrir-la-reussite-scolaire-comment-les-banques-alimentaires-soutiennent-les-programmes-de-repas-scolaires-au-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/foodbankscanada.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Nourrir la r\u00e9ussite scolaire\u202f: comment les banques alimentaires soutiennent les programmes de repas scolaires au Canada"}]},{"@type":"WebSite","@id":"https:\/\/foodbankscanada.ca\/fr\/#website","url":"https:\/\/foodbankscanada.ca\/fr\/","name":"Banques alimentaires Canada","description":"","publisher":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/foodbankscanada.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/foodbankscanada.ca\/fr\/#organization","name":"Food Banks Canada","url":"https:\/\/foodbankscanada.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","contentUrl":"https:\/\/fbcblobstorage.blob.core.windows.net\/wordpress\/2021\/11\/logo.png","width":377,"height":89,"caption":"Food Banks Canada"},"image":{"@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/6cc54c832653dce5f336a8e850d98f1f","name":"Samantha Rideout","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/foodbankscanada.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0436ecff73810150cca59d2521277072f37caf478cd16af70844347e0259cde6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0436ecff73810150cca59d2521277072f37caf478cd16af70844347e0259cde6?s=96&d=mm&r=g","caption":"Samantha Rideout"},"url":"https:\/\/foodbankscanada.ca\/fr\/author\/samantha-rideoutfoodbankscanada-ca\/"}]}},"_links":{"self":[{"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/posts\/49780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/comments?post=49780"}],"version-history":[{"count":6,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/posts\/49780\/revisions"}],"predecessor-version":[{"id":49794,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/posts\/49780\/revisions\/49794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media\/49786"}],"wp:attachment":[{"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=49780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/categories?post=49780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/foodbankscanada.ca\/fr\/wp-json\/wp\/v2\/tags?post=49780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}